{"id":5885,"date":"2018-01-26T13:19:40","date_gmt":"2018-01-26T12:19:40","guid":{"rendered":"https:\/\/www.carajandb.com\/?page_id=5885"},"modified":"2024-08-31T21:52:37","modified_gmt":"2024-08-31T19:52:37","slug":"free-oracle-and-postgresql-tutorials","status":"publish","type":"page","link":"https:\/\/carajandb.com\/en\/free-oracle-and-postgresql-tutorials\/","title":{"rendered":"Downloads"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-yuzarzed alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-euotcr2a\">\n<section class=\"wp-block-uagb-info-box uagb-block-3sx67h8e uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top wp-block-uagb-info-box--has-margin\"><div class=\"uagb-infobox-margin-wrapper\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title-prefix\">In-Depth Knowledge from Practice<\/p><h1 class=\"uagb-ifb-title\">Practical Materials Available for Free Download<\/h1><\/div><div class=\"uagb-ifb-desc\"><\/div><\/div><\/div><\/section>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-3bb3a957\">\n<div class=\"wp-block-uagb-image alignleft uagb-block-rjd2zjrb wp-block-uagb-image--layout-default wp-block-uagb-image--effect-zoomin wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" srcset=\"https:\/\/carajandb.com\/wp-content\/uploads\/2024\/08\/download-bereich-1024x672.webp ,https:\/\/carajandb.com\/wp-content\/uploads\/2024\/08\/download-bereich-scaled.webp 780w, https:\/\/carajandb.com\/wp-content\/uploads\/2024\/08\/download-bereich-scaled.webp 360w\" sizes=\"auto, (max-width: 480px) 150px\" src=\"https:\/\/carajandb.com\/wp-content\/uploads\/2024\/08\/download-bereich-1024x672.webp\" alt=\"Download icon on cube block on laptop\" class=\"uag-image-8915\" width=\"535\" height=\"390\" title=\"Download Area\" loading=\"lazy\" role=\"img\"\/><\/figure><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-mx6h9tra alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<h2 class=\"wp-block-heading has-ast-global-color-0-color has-text-color has-link-color wp-elements-1ff29b8928b450a0531c90105307f6dc\">In-Depth Knowledge from Practice<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In our download area, you will find a comprehensive collection of high-quality materials based on decades of experience in the database industry. These resources, developed from numerous projects and implementations, cover a wide range of topics\u2014from migration strategies and performance optimization to security concepts for Oracle and PostgreSQL.<br><br>Our goal is to provide you with access to this solid expertise, thereby elevating your database projects to a new level. Whether you are planning a complex migration, looking to improve your database performance, or searching for innovative solutions to specific problems, you will find valuable insights and actionable guidance here. Our materials are for you:<\/p>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-68a12b08\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-1843bf20\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>Free of Charge:<\/strong> All materials are available to you at no cost.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-37ef24fa\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>Always Up-to-Date:<\/strong> We continuously analyze new Oracle versions and PostgreSQL developments to provide you with timely and relevant information.<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-070c2beb\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\"><path d=\"M256 0C114.6 0 0 114.6 0 256c0 141.4 114.6 256 256 256s256-114.6 256-256C512 114.6 397.4 0 256 0zM406.6 278.6l-103.1 103.1c-12.5 12.5-32.75 12.5-45.25 0s-12.5-32.75 0-45.25L306.8 288H128C110.3 288 96 273.7 96 256s14.31-32 32-32h178.8l-49.38-49.38c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l103.1 103.1C414.6 241.3 416 251.1 416 256C416 260.9 414.6 270.7 406.6 278.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\"><strong>Practical and Diverse: <\/strong>Our content covers a wide range\u2014from fundamentals to advanced concepts\u2014and is based on real project experiences.<\/span><\/div>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-ast-global-color-0-color has-text-color has-link-color wp-elements-9de0c9f5f83d6a59a447458d42f2320a\">FILTER RESOURCES<\/h2>\n\n\n\n\n\n\n<div class=\"wp-block-columns has-medium-font-size is-layout-flex wp-container-core-columns-is-layout-011dba32 wp-block-columns-is-layout-flex\" style=\"margin-top:0;margin-bottom:0;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><div class=\"wp-block-uagb-loop-builder uagb-block-f5cb1249      alignwide\" data-block_id=\"f5cb1249\"  style=\"\"><div id=\"uagb-block-queryid-0\" data-query-id=\"0\" class=\"uagb-loop-container uagb-block-73c39048     \" style=\"\"><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><div class=\"uagb-loop-post\"><div class=\"uagb-loop-post-inner\">\n\n<div class=\"wp-block-uagb-container uagb-block-d6fa0472 alignfull uagb-is-root-container\">\n<div class=\"wp-block-uagb-container uagb-block-884dc2d4\">\n<div class=\"wp-block-uagb-container uagb-block-0af1d896\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3ef9f814\"><h2 class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_title\" data-spectra-dc-link=\"|\" class=\"uag-pro-dynamic-content\">Publikationen<\/span><\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-flex uagb-block-6a5ae285\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-57a981d1\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|post_date|post_date_gmt|m\/d\/Y\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3cdacfe7\"><p class=\"uagb-heading-text\"> <span data-spectra-dc-field=\"current_post|name\" class=\"uag-pro-dynamic-content\">No Content<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fafb0e1c\"><p class=\"uagb-heading-text\"><span data-spectra-dc-field=\"current_post|post_excerpt\" data-spectra-dc-advanced=\"|||120\" class=\"uag-pro-dynamic-content\">(No Content)<\/span><\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2ac4d47d\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-c94d0019 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Zur Download-Seite \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<\/div><\/div><\/div>\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2bacf358\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n\n\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-f9a1b58c wp-block-button\"><div class=\"uagb-button__wrapper\"><a id=\"uagb-pagination-links\" data-uagb-block-query-id=\"0\" data-uagb-block-query-paged=\"1\" class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">1<\/div><\/a><\/div><\/div>\n\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-f9a1b58c wp-block-button\"><div class=\"uagb-button__wrapper\"><a id=\"uagb-pagination-links\" data-uagb-block-query-id=\"0\" data-uagb-block-query-paged=\"2\" class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">2<\/div><\/a><\/div><\/div>\n\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-f9a1b58c wp-block-button\"><div class=\"uagb-button__wrapper\"><a id=\"uagb-pagination-links\" data-uagb-block-query-id=\"0\" data-uagb-block-query-paged=\"3\" class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">3<\/div><\/a><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-6c177952 wp-block-button\"><div class=\"uagb-button__wrapper\"><a id=\"uagb-pagination-links\" data-uagb-block-query-id=\"0\" data-uagb-block-query-paged=\"2\" class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Next<\/div><span class=\"uagb-button__icon uagb-button__icon-position-after\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\" aria-hidden=\"true\" focussable=\"false\"><path d=\"M246.6 233.4l-160-160c-12.5-12.5-32.75-12.5-45.25 0s-12.5 32.75 0 45.25L178.8 256l-137.4 137.4c-12.5 12.5-12.5 32.75 0 45.25C47.63 444.9 55.81 448 64 448s16.38-3.125 22.62-9.375l160-160C259.1 266.1 259.1 245.9 246.6 233.4zM438.6 233.4l-160-160c-12.5-12.5-32.75-12.5-45.25 0s-12.5 32.75 0 45.25L370.8 256l-137.4 137.4c-12.5 12.5-12.5 32.75 0 45.25C239.6 444.9 247.8 448 256 448s16.38-3.125 22.62-9.375l160-160C451.1 266.1 451.1 245.9 438.6 233.4z\"><\/path><\/svg><\/span><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-layout-grid uagb-block-005fba1f alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-12865cae\"><h3 class=\"uagb-heading-text\">Every database is unique, and so are our solutions!<\/h3><p class=\"uagb-desc-text\">Let\u2019s collaborate to upgrade your database and optimize your infrastructure for future success.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-2c953428\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-8bb4b826 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Schedule a free expert consultation \u2192<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In-Depth Knowledge from Practice In our download area, you will find a comprehensive collection of high-quality materials based on decades of experience in the database industry. These resources, developed from numerous projects and implementations, cover a wide range of topics\u2014from migration strategies and performance optimization to security concepts for Oracle and PostgreSQL. Our goal is to provide you with access to this solid expertise, thereby elevating your database projects to a new level. Whether you are planning a complex migration, looking to improve your database performance, or searching for innovative solutions to specific problems, you will find valuable insights and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_crdt_document":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-5885","page","type-page","status-publish","hentry"],"acf":[],"spectra_custom_meta":{"_edit_lock":["1725133958:8"],"_edit_last":["8"],"_wp_page_template":["default"],"_wpb_vc_js_status":["false"],"_yoast_wpseo_content_score":["90"],"layout_header":["light"],"_layout_header":["field_5a48111185e5f"],"layout_background":[""],"_layout_background":["field_5a481193c0995"],"layout_hide_services":["0"],"_layout_hide_services":["field_5a4811c5c0996"],"_wpml_location_migration_done":["1"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_wordproof_timestamp":[""],"_wpml_media_duplicate":["0"],"_wpml_media_featured":["0"],"_wpml_word_count":["{\"total\":212,\"to_translate\":{\"en\":212}}"],"astra_style_timestamp_css":["1777759867"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"rank_math_internal_links_processed":["1"],"rank_math_seo_score":["55"],"rank_math_title":["Free Oracle and PostgreSQL Tutorials: Download Expert Guides"],"rank_math_description":["Download free Oracle and PostgreSQL tutorials from experts. Access guides, books, and articles to enhance your database projects."],"rank_math_og_content_image":["a:2:{s:5:\"check\";s:32:\"37535ef4b9868dd01f358284d1832f1b\";s:6:\"images\";a:1:{i:0;s:79:\"https:\/\/carajandb.com\/wp-content\/uploads\/2024\/08\/download-bereich-1024x672.webp\";}}"],"rank_math_focus_keyword":["Free Oracle and PostgreSQL Tutorials"],"_last_translation_edit_mode":["native-editor"],"wpil_sync_report3":["1"],"wpil_links_inbound_internal_count":["0"],"wpil_links_inbound_internal_count_data":["eJxLtDKwqq4FAAZPAf4="],"wpil_links_outbound_internal_count":["6"],"wpil_links_outbound_internal_count_data":["eJzVVktrGzEQ\/i8q9Lb2vvzoGJNbTq1b6CFHoZVkW7EsqVotiQn+7x2ttsZJKLShNfFl0Yxmvnl8H4sYTOFJQb74CsUEyJ1Tmn6xQmr6WZkdgaKCpxZmQDSaVAmyiMEtVEA6rwmeZiWQbQgOxmMvNesM35Z5WY848+yeGdGMuN2PH1zGxF6ZsRQqjNzW3TjbBhoOTi7XSgfps1aGiFcjHF7FYzkF8nvMGDEHogwmG4a9NFCkfNfnr9BAAIbJ1sfgIgdym2p9T7XiyEwIKWhzoE53G2UiTJ6QteUsKGv6KYFwi5VMaiwfFvKwVa2TnnIvWZCn7RQF9tVS1gUbw87dwTO+U2Zztsvo3lvRaUmfRZdDkb7wY0j+o8Ip30zWtP4Tsm5+dNIfMiWWHds0WYOL2GW9T4ks\/6ckvZrkW3QPk+AC0hCT+aTCLIwMKmiZuEWMKB9yDtcz3gYWujYFnfO2ShBxOe0JokXWT1rhWvFfd\/MeUyUBrAaxWL9hRnGKLK7Xip8So6qjyFYDnYyv6cu6xhret358qUsgxfWqsXy7Gj\/N\/kKNeebYRi7Ljx\/yar6IZ7EsknE5uXooi1e\/FSDl9dJXXZa+6j3SV10vffVl6avfI3319dI3udi7q\/9mePPYv76e\/1P\/77sLjTupMPpaeTr+BG+OmOo="],"wpil_links_outbound_external_count":["0"],"wpil_links_outbound_external_count_data":["eJxLtDKwqq4FAAZPAf4="],"wpil_sync_report2_time":["2024-08-27T11:47:26+00:00"],"_wp_attachment_metadata":[""],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:4;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:2;s:18:\"uagb\/buttons-child\";i:4;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:8;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:1;s:20:\"uagb\/icon-list-child\";i:3;s:10:\"uagb\/image\";i:1;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:1;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:1;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:1;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_css_file_name":["uag-css-5885.css"],"_uag_js_file_name":["uag-js-5885.js"],"_uagb_last_spectra_edit":["1776960942"],"_uag_page_assets":["a:9:{s:3:\"css\";s:106258:\".wp-block-uagb-container.uagb-block-005fba1f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-005fba1f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-005fba1f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-005fba1f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-005fba1f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-005fba1f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-005fba1f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-005fba1f.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 20px;column-gap: 0px;grid-template-columns: minmax( 1px, 70%)  minmax( 1px, 30%) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: center;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-005fba1f{box-shadow: 0px 5px 40px -10px rgba(86,104,146,0.33) ;padding-top: 30px;padding-bottom: 30px;padding-left: 30px;padding-right: 30px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-top-left-radius: 0px;border-top-right-radius: 0px;border-bottom-left-radius: 0px;border-bottom-right-radius: 0px;border-color: inherit;background-color: var(--ast-global-color-1);;}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-5);}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading {padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading .uagb-desc-text{color: var(--ast-global-color-5);margin-bottom: 0px;}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12865cae .uagb-heading-text{margin-bottom: 20px;}.uagb-block-2c953428.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-2c953428.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: right;align-items: center;}.uagb-block-2c953428 .uagb-button__wrapper{margin-top: 10px;margin-bottom: 10px;margin-left: 10px;margin-right: 10px;}.wp-block-uagb-buttons .uagb-block-8bb4b826.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-6);}.wp-block-uagb-buttons .uagb-block-8bb4b826 .wp-block-button__link{background: var(--ast-global-color-6);}.wp-block-uagb-buttons .uagb-block-8bb4b826 .wp-block-button__link:hover{background: linear-gradient(0deg, var(--ast-global-color-2) 0%, var(--ast-global-color-8) 100%);;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .wp-block-button__link:focus{background: linear-gradient(0deg, var(--ast-global-color-2) 0%, var(--ast-global-color-8) 100%);;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-button__wrapper .uagb-buttons-repeater{color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #000;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #000;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater.wp-block-button__link{border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #000;border-style: none;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #333;}.wp-block-uagb-buttons .uagb-block-8bb4b826.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-left-radius: 2px;border-top-right-radius: 2px;border-bottom-left-radius: 2px;border-bottom-right-radius: 2px;border-color: #000;border-style: none;}.wp-block-uagb-buttons .uagb-block-8bb4b826.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #333;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-button__link{text-transform: normal;text-decoration: none;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-005fba1f{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-005fba1f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-005fba1f.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 30px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-005fba1f{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);;}.wp-block-uagb-container.uagb-block-005fba1f.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-005fba1f.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading {text-align: center;padding-top: 10px;padding-right: 10px;padding-bottom: 10px;padding-left: 10px;}.wp-block-uagb-advanced-heading.uagb-block-12865cae .uagb-heading-text{margin-bottom: 20px;}.uagb-block-2c953428.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-2c953428.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-2c953428 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 10px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .wp-block-button__link:hover{background: linear-gradient(0deg, var(--ast-global-color-2) 0%, var(--ast-global-color-8) 100%);;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .wp-block-button__link:focus{background: linear-gradient(0deg, var(--ast-global-color-2) 0%, var(--ast-global-color-8) 100%);;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8bb4b826.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #000;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #000;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-005fba1f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-005fba1f > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-005fba1f.uagb-layout-grid > .uagb-container-inner-blocks-wrap{row-gap: 30px;grid-template-columns: minmax( 1px, 1fr) ;grid-template-rows: minmax( 1px, 1fr) ;align-items: stretch;justify-items: stretch;align-content: stretch;justify-content: stretch;}.wp-block-uagb-container.uagb-block-005fba1f{padding-top: 15px;padding-bottom: 15px;padding-left: 15px;padding-right: 15px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 30px;order: initial;background-color: var(--ast-global-color-1);;}.wp-block-uagb-advanced-heading.uagb-block-12865cae.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-12865cae .uagb-heading-text{margin-bottom: 20px;}.uagb-block-2c953428.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-2c953428.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .wp-block-button__link:hover{background: linear-gradient(0deg, var(--ast-global-color-2) 0%, var(--ast-global-color-8) 100%);;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .wp-block-button__link:focus{background: linear-gradient(0deg, var(--ast-global-color-2) 0%, var(--ast-global-color-8) 100%);;background-clip: padding-box;}.wp-block-uagb-buttons .uagb-block-8bb4b826.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: none;border-color: #000;}.wp-block-uagb-buttons .uagb-block-8bb4b826 .uagb-buttons-repeater.wp-block-button__link{border-style: none;border-color: #000;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.uagb-ifb-content>svg *{-webkit-transition:all .2s;-o-transition:all .2s;transition:all .2s}.uagb-ifb-content>svg,.uagb-ifb-content{display:inline-block}.uagb-ifb-content>svg{vertical-align:middle;width:inherit;height:inherit;font-style:initial}.uagb-ifb-content .uagb-ifb-icon-wrap svg{box-sizing:content-box;width:inherit;height:inherit}.uagb-ifb-button-wrapper:empty{display:none}div.uagb-ifb-button-wrapper a.uagb-infobox-cta-link,div.uagb-ifb-cta a.uagb-infobox-cta-link,.entry .entry-content a.uagb-infobox-cta-link,a.uagb-infobox-link-wrap,.entry .entry-content a.uagb-infobox-link-wrap{text-decoration:none;align-items:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-middle .uagb-ifb-title-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-middle .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-middle .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-middle .uagb-ifb-content{-ms-flex-item-align:center;-webkit-align-self:center;align-self:center}.uagb-infobox-icon-left-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title.uagb-infobox-image-valign-top .uagb-ifb-title-wrap,.uagb-infobox-image-valign-top .uagb-ifb-icon-wrap,.uagb-infobox-image-valign-top .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-image-valign-top .uagb-ifb-content,.uagb-infobox-icon-right.uagb-infobox-image-valign-top .uagb-ifb-content{-webkit-align-self:self-start;align-self:self-start}.uagb-infobox-left{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-center{justify-content:center;text-align:center;-webkit-box-pack:center;-ms-flex-pack:center;-webkit-justify-content:center;-moz-box-pack:center}.uagb-infobox-right{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}.uagb-infobox-icon-above-title.uagb-infobox__content-wrap,.uagb-infobox-icon-below-title.uagb-infobox__content-wrap{display:block;width:100%}.uagb-infobox-icon-left-title .uagb-ifb-content>svg,.uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:10px}.uagb-infobox-icon-right-title .uagb-ifb-content>svg,.uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:10px}.uagb-infobox-icon-left.uagb-infobox__content-wrap,.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:-webkit-flex;display:-moz-box;display:flex;-js-display:flex}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-image-content,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-image-content,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{flex-shrink:0;line-height:0}.uagb-infobox-icon-left-title .uagb-ifb-left-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image .uagb-ifb-title-wrap,.uagb-infobox-icon-left .uagb-ifb-content,.uagb-infobox-icon-right .uagb-ifb-content{flex-grow:1}.uagb-infobox-icon-right.uagb-infobox__content-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}.uagb-ifb-content img{position:relative;display:inline-block;line-height:0;width:auto;height:auto !important;max-width:100%;border-radius:inherit;-webkit-box-sizing:content-box;-moz-box-sizing:content-box;-webkit-border-radius:inherit}.uagb-infobox-module-link{position:absolute;top:0;right:0;bottom:0;left:0;z-index:4;width:100%;height:100%}.uagb-edit-mode .uagb-infobox-module-link{z-index:2}.uagb-infobox-link-icon-after{margin-right:0;margin-left:5px}.uagb-infobox-link-icon-before{margin-right:5px;margin-left:0}.uagb-infobox-link-icon{-webkit-transition:all 200ms linear;transition:all 200ms linear}.uagb-infobox__content-wrap{box-sizing:border-box;position:relative;width:100%;word-break:break-word;z-index:1}.uagb-ifb-separator{display:inline-block;margin:0;border-top-color:#333;border-top-style:solid;border-top-width:2px;line-height:0}.uagb-ifb-button-wrapper{line-height:1}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link{background-color:unset;border:none}.uagb-ifb-button-wrapper.uagb-ifb-button-type-text .uagb-infobox-cta-link.wp-block-button__link:hover{background-color:unset;border-color:unset}.uagb-ifb-button-wrapper .uagb-infobox-cta-link{cursor:pointer}.uagb-ifb-button-wrapper .uagb-infobox-cta-link.wp-block-button__link{width:auto}.uagb-ifb-button-wrapper .wp-block-button__link svg,.uagb-ifb-button-wrapper .ast-outline-button svg{fill:currentColor}.uagb-infobox__content-wrap a{-webkit-box-shadow:none;box-shadow:none;text-decoration:none}.uagb-ifb-title-wrap{width:100%}.uagb-ifb-title{margin-block-start:0}.uagb-ifb-title-wrap .uagb-ifb-title-prefix{display:block;padding:0;margin:0}.uagb-infobox__content-wrap.uagb-infobox__content-wrap{position:relative}.uagb-ifb-content{width:100%}.uagb-infobox__content-wrap.uagb-infobox,.uagb-ifb-content,.uagb-ifb-title-wrap,.uagb-ifb-title-prefix *,svg.dashicon.dashicons-upload{z-index:1}a.uagb-infobox-link-wrap{color:inherit}.uagb-ifb-content p:empty{display:none}.uagb-infobox__content-wrap .uagb-ifb-content img{display:inline-block;max-width:100%}.uagb-infobox__content-wrap .uagb-ifb-content svg{display:inline-block}.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-image-content,.uagb-infobox-icon-right .uagb-ifb-image-content{box-sizing:content-box}.uagb-infobox-cta-link>svg{vertical-align:middle;width:15px;height:15px;font-size:15px}.uagb-infobox-cta-link{display:inline-flex}.block-editor-page #wpwrap .uagb-infobox-cta-link svg,.uagb-infobox-cta-link svg{font-style:normal}.uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}.uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,.uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-icon-wrap{margin-left:10px;line-height:0}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-icon-wrap,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-icon-wrap{margin-right:10px;line-height:0}html[dir=rtl] .uagb-infobox-left{justify-content:flex-end;text-align:right;-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end}html[dir=rtl] .uagb-infobox-right{justify-content:flex-start;text-align:left;-webkit-box-pack:start;-ms-flex-pack:start;-webkit-justify-content:flex-start;-moz-box-pack:start}.uagb-infobox-icon-left .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-left-title .uagb-ifb-left-title-image,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{display:-webkit-box;display:-ms-flexbox;display:flex}.uagb-infobox-icon-right .uagb-ifb-left-right-wrap,.uagb-infobox-icon-right-title .uagb-ifb-right-title-image{-webkit-box-pack:end;-ms-flex-pack:end;-webkit-justify-content:flex-end;-moz-box-pack:end;justify-content:flex-end}a.uagb-infbox__link-to-all{position:absolute;top:0;left:0;z-index:3;width:100%;height:100%;box-shadow:none;text-decoration:none;-webkit-box-shadow:none}@media only screen and (max-width: 976px){.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{padding:0;margin-bottom:20px}.uagb-infobox-stacked-tablet.uagb-reverse-order-tablet.uagb-infobox__content-wrap{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-content,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{display:block;width:100%;text-align:center}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap .uagb-ifb-image-content{margin-right:0;margin-left:0}.uagb-infobox-stacked-tablet.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-tablet .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}@media screen and (max-width: 767px){.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap{display:inline-block}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap{padding:0;margin-bottom:20px;margin-right:0;margin-left:0}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap.uagb-reverse-order-mobile{display:-webkit-inline-box;display:-ms-inline-flexbox;display:-webkit-inline-flex;display:-moz-inline-box;display:inline-flex;flex-direction:column-reverse;-js-display:inline-flex;-webkit-box-orient:vertical;-webkit-box-direction:reverse;-ms-flex-direction:column-reverse;-webkit-flex-direction:column-reverse;-moz-box-orient:vertical;-moz-box-direction:reverse}.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-image-content,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-icon-wrap,.uagb-infobox-stacked-mobile.uagb-infobox__content-wrap .uagb-ifb-content{display:block;width:100%;text-align:center}.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-left.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-right:0}.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right-title.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-image-content,.uagb-infobox-icon-right.uagb-infobox-stacked-mobile .uagb-ifb-icon-wrap{margin-left:0}.uagb-infobox-icon-left-title .uagb-ifb-separator{margin:10px 0}}.uagb-ifb-icon svg{width:inherit;height:inherit;vertical-align:middle}.uagb-ifb-button-icon{height:15px;width:15px;font-size:15px;vertical-align:middle}.uagb-ifb-button-icon svg{height:inherit;width:inherit;display:inline-block}.uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:right}.uagb-ifb-cta-button{display:inline-block}.uagb-disable-link{pointer-events:none}@media only screen and (min-width: 977px){.uagb-infobox-margin-wrapper{display:flex}}.uagb-ifb-content .uagb-ifb-desc p:last-child{margin-bottom:0}html[dir=rtl] .uagb-infobox-icon-left-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-left .uagb-ifb-content>svg{margin-right:0;margin-left:10px}html[dir=rtl] .uagb-infobox-icon-right-title .uagb-ifb-content>svg,html[dir=rtl] .uagb-infobox-icon-right .uagb-ifb-content>svg{margin-left:0;margin-right:10px}html[dir=rtl] .uagb-infobox-link-icon-after{margin-right:5px;margin-left:0}html[dir=rtl] .uagb-infobox-link-icon-before{margin-right:0;margin-left:5px}html[dir=rtl] .uagb-ifb-button-icon.uagb-ifb-align-icon-after{float:left}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.wp-block-uagb-container.uagb-block-yuzarzed .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-yuzarzed .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-yuzarzed .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-yuzarzed .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-yuzarzed .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-yuzarzed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-yuzarzed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-yuzarzed{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-0);;row-gap: 0px;column-gap: 72px;}.wp-block-uagb-container.uagb-block-euotcr2a .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-euotcr2a .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-euotcr2a .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-euotcr2a .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-euotcr2a .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-euotcr2a{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-euotcr2a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-euotcr2a{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.uagb-block-3sx67h8e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3sx67h8e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;color: #333;}.uagb-block-3sx67h8e .uagb-ifb-icon svg{fill: #333;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3sx67h8e .uagb-ifb-content .uagb-ifb-icon-wrap svg{line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3sx67h8e .uagb-iconbox-icon-wrap{margin: auto;display: inline-flex;align-items: center;justify-content: center;box-sizing: content-box;width: 30px;height: 30px;line-height: 30px;padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3sx67h8e .uagb-ifb-content .uagb-ifb-left-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3sx67h8e .uagb-ifb-content .uagb-ifb-right-title-image svg{width: 30px;line-height: 30px;font-size: 30px;color: #333;fill: #333;}.uagb-block-3sx67h8e .uagb-infobox__content-wrap .uagb-ifb-imgicon-wrap{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;}.uagb-block-3sx67h8e .uagb-infobox .uagb-ifb-image-content img{border-radius: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-left: 0px;padding-right: 0px;padding-top: 0px;padding-bottom: 0px;border-radius: 0px;}.uagb-block-3sx67h8e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{color: var(--ast-global-color-4);margin-bottom: 10px;margin-top: 5px;margin-left: 0px;margin-right: 0px;}.uagb-block-3sx67h8e.wp-block-uagb-info-box .uagb-ifb-title{color: var(--ast-global-color-5);margin-bottom: 10px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3sx67h8e.wp-block-uagb-info-box .uagb-ifb-desc{color: var(--ast-global-color-5);margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 15px;}.uagb-block-3sx67h8e .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;margin-bottom: 0px;}.uagb-block-3sx67h8e .uagb-infobox__content-wrap .uagb-ifb-separator{width: 30%;border-top-width: 2px;border-top-color: #333;border-top-style: solid;}.uagb-block-3sx67h8e .uagb-ifb-align-icon-after{margin-left: 5px;}.uagb-block-3sx67h8e .uagb-ifb-align-icon-before{margin-right: 5px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content svg{box-sizing: content-box;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3sx67h8e .uagb-infobox__content-wrap{text-align: left;}.uagb-block-3sx67h8e.uagb-infobox-icon-above-title{text-align: left;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-3sx67h8e .uagb-ifb-title{font-weight: 700;font-size: 38px;}.uagb-block-3sx67h8e .uagb-ifb-title-prefix{text-transform: uppercase;font-weight: 500;font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-3sx67h8e .uagb-iconbox-icon-wrap{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-right-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-left-title-image > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content > img{padding-right: 0px;padding-left: 0px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap{text-align: right;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox-icon-above-title{text-align: right;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-block-3bb3a957 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3bb3a957 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3bb3a957 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3bb3a957 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3bb3a957 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3bb3a957{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3bb3a957 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3bb3a957{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 32px;column-gap: 0px;}.uagb-block-rjd2zjrb.wp-block-uagb-image{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;text-align: left;justify-content: flex-start;align-self: flex-start;}.uagb-block-rjd2zjrb .wp-block-uagb-image__figure{align-items: flex-start;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-default figure img{box-shadow: 10px 10px 0px 0px var(--ast-global-color-6);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-style: solid;}.uagb-block-rjd2zjrb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 10px 10px 0px 0px var(--ast-global-color-6);border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-style: solid;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 8px;border-top-right-radius: 8px;border-bottom-left-radius: 8px;border-bottom-right-radius: 8px;border-style: solid;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-rjd2zjrb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-rjd2zjrb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 535px;height: 390px;}.uagb-block-rjd2zjrb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-rjd2zjrb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.wp-block-uagb-container.uagb-block-mx6h9tra .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-mx6h9tra .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-mx6h9tra .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-mx6h9tra .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-mx6h9tra .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-mx6h9tra{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-mx6h9tra > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-mx6h9tra{box-shadow: 0px 0px   #00000070 ;padding-top: 112px;padding-bottom: 112px;padding-left: 40px;padding-right: 40px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-5);;row-gap: 48px;column-gap: 0px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-radius: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child .uagb-icon-list__label{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child{text-decoration: !important;line-height: em;}.wp-block-uagb-icon-list.uagb-block-68a12b08.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-1843bf20.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-1843bf20.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-37ef24fa.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-37ef24fa.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-070c2beb.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-070c2beb.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-73c39048.uagb-loop-container{flex-direction: row;gap: 20px;}.uagb-block-73c39048.uagb-loop-container > .uagb-loop-post{width: calc( calc(100% - 2 * 20px ) \/ 3 );}.wp-block-uagb-container.uagb-block-d6fa0472 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d6fa0472 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d6fa0472 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-d6fa0472 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-d6fa0472 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d6fa0472{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d6fa0472{box-shadow: 0px 0px   rgba(16,24,41,0.1) ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-884dc2d4 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-884dc2d4 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-884dc2d4 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-884dc2d4 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-884dc2d4 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-884dc2d4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-884dc2d4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: stretch;justify-content: space-between;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-884dc2d4{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-style: none;border-color: inherit;background-color: var(--ast-global-color-4);;flex-direction: column;align-items: stretch;justify-content: space-between;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-0af1d896 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0af1d896 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0af1d896 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0af1d896 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0af1d896 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0af1d896{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0af1d896 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 10px;column-gap: 10px;}.wp-block-uagb-container.uagb-block-0af1d896{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: flex-start;flex-wrap: nowrap;row-gap: 10px;column-gap: 10px;}.wp-block-uagb-advanced-heading.uagb-block-3ef9f814.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-3ef9f814.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-0);}.wp-block-uagb-advanced-heading.uagb-block-3ef9f814.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3ef9f814.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3ef9f814.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3ef9f814.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3ef9f814 .uagb-heading-text{text-decoration: none;font-weight: 600;font-size: 26px;}.wp-block-uagb-container.uagb-block-6a5ae285 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a5ae285 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a5ae285 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-6a5ae285 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-6a5ae285 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a5ae285{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a5ae285 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1200px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6a5ae285{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-6a5ae285.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: auto !important;}.wp-block-uagb-container.uagb-block-6a5ae285.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: auto !important;}.wp-block-uagb-advanced-heading.uagb-block-57a981d1.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-57a981d1.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 20px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-57a981d1.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-57a981d1.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-57a981d1.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-57a981d1.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-57a981d1.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-57a981d1 .uagb-heading-text{font-size: 16px;}.wp-block-uagb-advanced-heading.uagb-block-3cdacfe7.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-3cdacfe7.wp-block-uagb-advanced-heading a{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-3cdacfe7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3cdacfe7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3cdacfe7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3cdacfe7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3cdacfe7 .uagb-heading-text{font-size: 16px;}.wp-block-uagb-advanced-heading.uagb-block-fafb0e1c.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-8);}.wp-block-uagb-advanced-heading.uagb-block-fafb0e1c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fafb0e1c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fafb0e1c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fafb0e1c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fafb0e1c .uagb-heading-text{font-size: 16px;}.uagb-block-2ac4d47d.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-2ac4d47d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: left;align-items: center;}.uagb-block-2ac4d47d .uagb-button__wrapper{margin-left: 0px;}.wp-block-uagb-buttons .uagb-block-c94d0019.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-c94d0019 .wp-block-button__link{background: var(--ast-global-color-0);}.wp-block-uagb-buttons .uagb-block-c94d0019 .wp-block-button__link:hover{background: var(--ast-global-color-6);}.wp-block-uagb-buttons .uagb-block-c94d0019 .wp-block-button__link:focus{background: var(--ast-global-color-6);}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-button__wrapper .uagb-buttons-repeater{font-size: 16px;color: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-c94d0019 .wp-block-button__link.has-text-color:hover .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-c94d0019 .wp-block-button__link.has-text-color:focus .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 0px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 0px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: #726dab;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: #726dab;}.wp-block-uagb-buttons .uagb-block-c94d0019.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 0px;border-left-width: 0px;border-right-width: 0px;border-bottom-width: 0px;border-top-left-radius: 5px;border-top-right-radius: 5px;border-bottom-left-radius: 5px;border-bottom-right-radius: 5px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-c94d0019.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: #726dab;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-5);font-size: 16px;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater:hover .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater:focus .uagb-button__link{color: #ffffff;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-5);}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater:hover .uagb-button__icon > svg{fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater:focus .uagb-button__icon > svg{fill: #ffffff;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-button__link{text-transform: normal;text-decoration: none;}.uagb-block-2bacf358.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-2bacf358.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-2bacf358 .uagb-button__wrapper{margin-top: 20px;margin-bottom: 20px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-703e5ae1 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-703e5ae1 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #FFFFFF;}.wp-block-uagb-buttons .uagb-block-703e5ae1 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-703e5ae1 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-f9a1b58c .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-f9a1b58c .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #FFFFFF;}.wp-block-uagb-buttons .uagb-block-f9a1b58c .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-f9a1b58c .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-6c177952 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-6c177952 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #FFFFFF;}.wp-block-uagb-buttons .uagb-block-6c177952 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-6c177952 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-yuzarzed{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-yuzarzed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;column-gap: 40px;}.wp-block-uagb-container.uagb-block-yuzarzed{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-0);;column-gap: 40px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-euotcr2a{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-euotcr2a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;}.wp-block-uagb-container.uagb-block-euotcr2a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;}.uagb-block-3sx67h8e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 20px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3sx67h8e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3sx67h8e.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 8px;margin-right: 8px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3sx67h8e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3sx67h8e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3sx67h8e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3sx67h8e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-3sx67h8e .uagb-ifb-title-prefix{font-size: 16px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3bb3a957{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3bb3a957 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 24px;}.wp-block-uagb-container.uagb-block-3bb3a957{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 24px;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-default figure img{border-style: solid;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay figure img{border-style: solid;}.uagb-block-rjd2zjrb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 313px;height: 250px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-mx6h9tra{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-mx6h9tra > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 20px;}.wp-block-uagb-container.uagb-block-mx6h9tra{padding-top: 80px;padding-bottom: 80px;padding-left: 32px;padding-right: 32px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;row-gap: 20px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-68a12b08.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.uagb-block-73c39048.uagb-loop-container{flex-direction: row;gap: 24px;}.uagb-block-73c39048.uagb-loop-container > .uagb-loop-post{width: calc( calc(100% - 1 * 24px ) \/ 2 );}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d6fa0472{width: 100%;}.wp-block-uagb-container.uagb-block-d6fa0472{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;justify-content: flex-start;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-884dc2d4{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-884dc2d4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;}.wp-block-uagb-container.uagb-block-884dc2d4{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: none;background-color: var(--ast-global-color-4);;align-items: stretch;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0af1d896{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0af1d896 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;}.wp-block-uagb-container.uagb-block-0af1d896{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: center;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a5ae285{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a5ae285 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-6a5ae285{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.uagb-block-2ac4d47d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-2ac4d47d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-c94d0019.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.uagb-block-2bacf358.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-2bacf358.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-yuzarzed{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-yuzarzed > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap-reverse;row-gap: 40px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-yuzarzed{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 40px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-0);;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-euotcr2a{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-euotcr2a > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-euotcr2a{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;}.uagb-block-3sx67h8e .uagb-ifb-title-wrap .uagb-ifb-title-prefix{margin-bottom: 16px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3sx67h8e.wp-block-uagb-info-box .uagb-ifb-title{margin-bottom: 12px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3sx67h8e.wp-block-uagb-info-box .uagb-ifb-desc{margin-bottom: 0px;margin-top: 0px;margin-left: 0px;margin-right: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-icon-wrap > svg{width: 30px;height: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content .uagb-ifb-icon-wrap > svg{line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e .uagb-ifb-content .uagb-ifb-left-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e .uagb-ifb-content .uagb-ifb-right-title-image > svg{width: 30px;line-height: 30px;font-size: 30px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-ifb-content img{box-sizing: content-box;}.uagb-block-3sx67h8e .uagb-ifb-icon{width: 30px;line-height: 30px;}.uagb-block-3sx67h8e .uagb-ifb-icon > span{font-size: 30px;width: 30px;line-height: 30px;}.uagb-block-3sx67h8e .uagb-iconbox-icon-wrap{width: 30px;height: 30px;line-height: 30px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap:not(.wp-block-uagb-info-box--has-margin){padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap.wp-block-uagb-info-box--has-margin .uagb-infobox-margin-wrapper{padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg {margin-left: 5px;}.uagb-block-3sx67h8e .uagb-ifb-title{font-size: 27px;}.uagb-block-3sx67h8e .uagb-ifb-title-prefix{font-size: 15px;line-height: 1em;letter-spacing: 2px;}[dir=rtl] .uagb-block-3sx67h8e.uagb-infobox__content-wrap .uagb-infobox-cta-link > svg{margin-right: 5px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3bb3a957{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3bb3a957 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 24px;}.wp-block-uagb-container.uagb-block-3bb3a957{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 24px;order: initial;flex-wrap: wrap;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-default figure img{border-style: solid;}.uagb-block-rjd2zjrb.wp-block-uagb-image--layout-overlay figure img{border-style: solid;}.uagb-block-rjd2zjrb.wp-block-uagb-image .wp-block-uagb-image__figure img{object-fit: cover;width: 283px;height: 150px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-mx6h9tra{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-mx6h9tra > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-mx6h9tra{padding-top: 64px;padding-bottom: 64px;padding-left: 24px;padding-right: 24px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-5);;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-68a12b08 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-68a12b08.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 10px;}.uagb-block-73c39048.uagb-loop-container{flex-direction: column;gap: 32px;}.uagb-block-73c39048.uagb-loop-container > .uagb-loop-post{width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-d6fa0472{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-d6fa0472{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;justify-content: flex-start;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-884dc2d4{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-884dc2d4 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-884dc2d4{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;border-style: none;background-color: var(--ast-global-color-4);;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0af1d896{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0af1d896 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-0af1d896{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: center;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-6a5ae285{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-6a5ae285 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-6a5ae285{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.uagb-block-2ac4d47d.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-2ac4d47d.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-c94d0019.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-c94d0019 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.uagb-block-2bacf358.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-2bacf358.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{border-color: #28368200;padding: 0px;border-radius: 100px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-0) !important;color: var(--ast-global-color-0) !important;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-375284f0.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-375284f0.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dfc53cb7.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dfc53cb7.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{border-color: #28368200;padding: 0px;border-radius: 100px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-0) !important;color: var(--ast-global-color-0) !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-66131845.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-66131845.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-add44f6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-add44f6f{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{border-color: #28368200;padding: 0px;border-radius: 100px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-wrap{margin-right: 20px;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-0) !important;color: var(--ast-global-color-0) !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-66131845.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-66131845.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-bb602a54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-bb602a54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-add44f6f{width: 100%;}.wp-block-uagb-container.uagb-block-add44f6f{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;max-width:  !important;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-add44f6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-add44f6f{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8cad69e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e8cad69e{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8cad69e{width: 100%;}.wp-block-uagb-container.uagb-block-e8cad69e{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8cad69e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e8cad69e{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0921a5e7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0921a5e7{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-0921a5e7{width: 100%;}.wp-block-uagb-container.uagb-block-0921a5e7{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-0921a5e7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0921a5e7{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}}\";s:2:\"js\";s:557:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-8bb4b826' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-c94d0019' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-703e5ae1' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-f9a1b58c' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-6c177952' );\n});\n });\";s:18:\"current_block_list\";a:23:{i:0;s:14:\"uagb\/container\";i:2;s:13:\"uagb\/info-box\";i:4;s:10:\"uagb\/image\";i:6;s:12:\"core\/heading\";i:7;s:14:\"core\/paragraph\";i:8;s:14:\"uagb\/icon-list\";i:9;s:20:\"uagb\/icon-list-child\";i:10;s:14:\"core\/shortcode\";i:11;s:12:\"core\/columns\";i:12;s:11:\"core\/column\";i:13;s:17:\"uagb\/loop-builder\";i:14;s:17:\"uagb\/loop-wrapper\";i:18;s:21:\"uagb\/advanced-heading\";i:19;s:12:\"uagb\/buttons\";i:20;s:18:\"uagb\/buttons-child\";i:21;s:15:\"core\/categories\";i:22;s:17:\"core\/latest-posts\";i:23;s:14:\"core\/tag-cloud\";i:24;s:11:\"core\/search\";i:25;s:9:\"core\/list\";i:26;s:14:\"core\/list-item\";i:27;s:10:\"core\/group\";i:28;s:10:\"core\/image\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778700834\";s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:77:\"https:\/\/fonts.googleapis.com\/css?family=Default&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/carajandb.com\/en\/author\/7f95fa94393a2c00\/"},"uagb_comment_info":0,"uagb_excerpt":"In-Depth Knowledge from Practice In our download area, you will find a comprehensive collection of high-quality materials based on decades of experience in the database industry. These resources, developed from numerous projects and implementations, cover a wide range of topics\u2014from migration strategies and performance optimization to security concepts for Oracle and PostgreSQL. Our goal is&hellip;","_links":{"self":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/pages\/5885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/comments?post=5885"}],"version-history":[{"count":12,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/pages\/5885\/revisions"}],"predecessor-version":[{"id":9560,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/pages\/5885\/revisions\/9560"}],"wp:attachment":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/media?parent=5885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}