{"id":7677,"date":"2020-04-23T16:52:57","date_gmt":"2020-04-23T14:52:57","guid":{"rendered":"https:\/\/www.carajandb.com\/?p=7677"},"modified":"2020-05-11T16:23:19","modified_gmt":"2020-05-11T14:23:19","slug":"oracle-12-2-0-1-support-extended","status":"publish","type":"post","link":"https:\/\/carajandb.com\/en\/2020\/04\/23\/oracle-12-2-0-1-support-extended\/","title":{"rendered":"Oracle 12.2.0.1 Support Extended"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">April 15th was patch day again. New security patches, patch sets, release update and whatever they are named became available. On the same day Oracle announced that for 12.2.0.1 a &#8220;Limited Error Correction Support&#8221; will be offered.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Limited Error Correction Support<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">According to Oracle the reason for this support extension is to give customers more time to upgrade from version 12.2.0.1 to version 19. It doesn&#8217;t include version 18 or any other release. The support extension will start on December 1st 2020 and will last until March 31st 2022. And it only includes security patches and fixes for severity 1 issues. It&#8217;s not an equivalent to extended support which is available for the long term support releases like 12.1.0.2 or 19. More details can be found in My Oracle Support <a rel=\"noreferrer noopener\" href=\"https:\/\/support.oracle.com\/epmos\/faces\/DocumentDisplay?id=742060.1\" target=\"_blank\">MOS Note:742060.1<\/a> and of course in Mike Dietrich &#8216;s blog (<a href=\"https:\/\/mikedietrichde.com\/2020\/04\/15\/oracle-12-2-0-1-support-extended-with-limited-error-correction-support\/\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/mikedietrichde.com\/2020\/04\/15\/oracle-12-2-0-1-support-extended-with-limited-error-correction-support<\/a>). And also the plublicly available Lifetime Support Technology Document <a href=\"http:\/\/www.oracle.com\/us\/support\/library\/lifetime-support-technology-069183.pdf\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">http:\/\/www.oracle.com\/us\/support\/library\/lifetime-support-technology-069183.pdf<\/a> has been changed accordingly.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quote from the Lifetime Support Technology Document:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Oracle Database 12.2.0.1: Premier Support error correction provided for the period of December 1, 2020 through March 31, 2022 will be limited to Severity 1 production fixes and security fixes delivered via the Quarterly Release Update (RU) process.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Standard Edition and RAC<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">My general opinion is that there are good reasons to upgrade to version 19. Not only that it&#8217;s supported until March 2023 or with extended support until March 2026. But with 19c Real Application Clusters (RAC) is no longer available in Standard Edition Two. More infos can be found here: <a href=\"https:\/\/carajandb.com\/en\/blog\/2019\/no-rac-for-standard-edition\/\">https:\/\/carajandb.com\/en\/blog\/2019\/no-rac-for-standard-edition<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Those customers who are using Standard Edition with RAC have more time to look for an alternative. Most recently Markus Michalewicz (Oracle Senior Director of Product Management) announced a new High Availabilty Solution for Standard Edition: <a href=\"https:\/\/blogs.oracle.com\/maa\/standard-edition-2-announcing-standard-edition-high-availability\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">https:\/\/blogs.oracle.com\/maa\/standard-edition-2-announcing-standard-edition-high-availability<\/a>. But that doesn&#8217;t exist yet. PostgreSQL might be an alternative. But such a migration will probably take some time as well.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conclusion<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Many customers will greatly appreciate this announcement. Thank you Oracle! But this shouldn&#8217;t imply that there is no need to continue contemplaning the upgrade or migration of your existing database. Oracle version 20 will no longer support NON-CDB databases. It&#8217;s time to become familiar with the Multitenant Database architecture. As announced last year you can run up to three pluggable databases in one CDB without any additional options even in Standard Edition. Some more facts about that are listed here: <a href=\"https:\/\/carajandb.com\/en\/blog\/2019\/multitenant-for-everybody\/\">https:\/\/carajandb.com\/en\/blog\/2019\/multitenant-for-everybody\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Stay Heathy!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>April 15th was patch day again. New security patches, patch sets, release update and whatever they are named became available. On the same day Oracle announced that for 12.2.0.1 a &#8220;Limited Error Correction Support&#8221; will be offered. Limited Error Correction Support According to Oracle the reason for this support extension is to give customers more time to upgrade from version 12.2.0.1 to version 19. It doesn&#8217;t include version 18 or any other release. The support extension will start on December 1st 2020 and will last until March 31st 2022. And it only includes security patches and fixes for severity 1 [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[406],"tags":[181,460],"class_list":["post-7677","post","type-post","status-publish","format-standard","hentry","category-oracle-en","tag-standard-edition","tag-support"],"acf":{"occupation":"Write the Occupation of the Person","person_can-be-speaker":true,"person_is-team":true,"person_related-user-account":null,"person_ordering-number":50,"publication_speakers":null,"publication_content-language":["de"],"publication_files":null,"publication_event":"","publication_date":null},"spectra_custom_meta":{"_edit_lock":["1589206876:6"],"_edit_last":["6"],"layout_header":["light"],"_layout_header":["field_5a48111185e5f"],"layout_background":[""],"_layout_background":["field_5a481193c0995"],"layout_hide_services":["0"],"_layout_hide_services":["field_5a4811c5c0996"],"layout_show-author-box":["1"],"_layout_show-author-box":["field_5a64ee9cc6490"],"layout_show-categories-tags":["1"],"_layout_show-categories-tags":["field_5a64eee4c6491"],"blogpost_related-publications":[""],"_blogpost_related-publications":["field_5a480debdac62"],"blogpost_related-files":[""],"_blogpost_related-files":["field_5a480f377db29"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_yoast_wpseo_content_score":["60"],"_wpml_location_migration_done":["1"],"_yoast_wpseo_primary_category":["406"],"_encloseme":["1"],"_wpml_word_count":["{\"total\":427,\"to_translate\":{\"de\":427}}"],"rank_math_primary_category":["406"],"rank_math_news_sitemap_robots":["index"],"rank_math_robots":["a:1:{i:0;s:5:\"index\";}"],"astra_style_timestamp_css":["1777791600"],"rank_math_internal_links_processed":["1"],"wpil_sync_report3":["1"],"wpil_links_inbound_internal_count":["1"],"wpil_links_inbound_internal_count_data":["eJx1Ustu2zAQ\/JWAd8kiEyfG+heaB5BDjwRNUTIbmhTIZdog8N\/0M3rLj3UpKo6TojfuamZ2drQKOLxa6Lb3wNfAvk\/WydvQGye\/Wf\/EgF\/Ca4IbYI5KaXu2LeAEl8BydIxeN\/TcI06wWkXjVPZ6Lzpx1WoV1Q\/l+12rw2GV8jSFiM8mOmX8aGL2YzNkExsuGtF0DW\/3eJgFr0gvJCxPcQ3s\/6IFsQFmPZroFXF3wCt\/mvn\/rPRQ2stKgojzNuvNdVmIkGjRGba9qxr4Mhl2LpeA3CRUmFMFUSo60HCPtV7XlNJJIrk81oKY2ln9\/m0za1q0wddGMRriqLzVEqMaBqtPRNNbDHHBcWBKD\/LrXB+8nq0fZ4qivAqF\/hPZePzI\/u33kv3F8PYnXnDRirZrOVssqL43vdy9yImcW18S7apdF7Sqdj\/vTUF2y3H83Ns0mSh1NArN6VKKZZukyhgK7LxNm+on68ezuyrtQ+izM\/ITWixD5sG\/sPaPx7\/qdeOI"],"wpil_links_outbound_internal_count":["2"],"wpil_links_outbound_internal_count_data":["eJzVUctSwzAM\/BffUydpoaD+Ao8jR49im9bUsTKOA3Q6\/XfkpDDlwAGmHHqTNLur1Qqhhr2DcvUI1RWIp855dU\/GenXnwlZANYd9D0sQnlvljFhlcA9zEEP0gqsl0zYpdSBltB6HoDd1WS9mGiO+YDDNTFMrbZCNp7Wsy+pWBioi6uKZYtEnhmA0hTUuOQoySy5YkfqUy\/oaxM+yGXEDwoVkY0C200A18buR\/8ANCyCTKY5mF+c0mxVzamiMNarZqc4PaxeyjXJy5knjJ5JD1MROw3RYecz0beP6zkalo8VkvwKuKr6rVzgkyrDTcWI\/WxfWJ+\/I45bM4K36hq6PS8bF72maHxyn9Pd\/z38dYTv45PhwDGnM0b7auGvI7P772+e2eonPPnwA2g9G3A=="],"wpil_links_outbound_external_count":["4"],"wpil_links_outbound_external_count_data":["eJzVU8tu2zAQ\/JVCd5qk5PjBoOglxzwOPfQoUCRtLUyRAklFNYL8e1eynbh2LnHRAD6JWi53Zmd2pZiKFxDs9knwG5H9asGWD14bW96D22SCF+IlirnILP6WoLPbITmKQmRdsBmeZjOR1Sm1UVAau7b1IU18kMqaifINNW3jI11JZSK986prjEt3EFsrtz9Af59PczZjEz5UmmIhH9Nw5AuRnRcbbvACXDLBSUSvRi74rh3fPQ50RCadqn0YyyDxh6ef3x59MuIYauhVam10WW3L1nZrcIdqCGC9kgm8GzKxgvII6EZeOdsr0dfYgwmlCkYm8yYL50gvlrJLfkg7DidsYwNufSTiEG687qwp\/8rO9yAj8O+0i7+C4Je7xNny3aYGNkaDSQFUrXc25SxnlE0pv6E7vQnPSU4Y4WTvA0EmxqFkpIdUEwsNYOPEhOADUT4EowbNDun0A0fPcT\/vKFt8bR\/XOy355dMy3w8Latz3\/fE6d\/Gw5NRCFWTY4ndlEjTmTeBkVO289estYbMlXxSTVq9OxwGl+YfF\/k8Er9Po4nKjl8X7NlUoSDyWspGSxiSdlgH3Q8O4FjmRzvnOKeRMzm5rWNdEPkuwsgILaXtqO7p4ivNp87+E9DWOwusfJdqY3g=="],"wpil_sync_report2_time":["2024-08-27T11:47:24+00:00"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"copied_media_ids":["a:0:{}"],"referenced_media_ids":["a:0:{}"],"_uag_css_file_name":["uag-css-7677.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:25293:\".uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{border-color: #28368200;padding: 0px;border-radius: 100px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-0) !important;color: var(--ast-global-color-0) !important;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-d4bae936.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-375284f0.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-375284f0.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dfc53cb7.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-dfc53cb7.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{border-color: #28368200;padding: 0px;border-radius: 100px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-wrap{margin-right: 15px;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-0) !important;color: var(--ast-global-color-0) !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-66131845.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-66131845.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 20px;height: 20px;font-size: 20px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: center;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}.wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-add44f6f .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-add44f6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-add44f6f{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: stretch;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;color: var(--ast-global-color-0);fill: var(--ast-global-color-0);}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{border-color: #28368200;padding: 0px;border-radius: 100px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 20px;text-decoration: !important;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child{text-decoration: !important;font-size: 20px;line-height: 1.5em;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-wrap{margin-right: 20px;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: var(--ast-global-color-0) !important;color: var(--ast-global-color-0) !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-05f838d1.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child.wp-block-uagb-icon-list-child{margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.uagb-block-66131845.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-66131845.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-bb602a54.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-bb602a54.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b2264876.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-add44f6f{width: 100%;}.wp-block-uagb-container.uagb-block-add44f6f{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;max-width:  !important;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-add44f6f{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-add44f6f{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;align-items: stretch;flex-wrap: wrap;max-width: 100% !important;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__source-image{width: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 25px;height: 25px;font-size: 25px;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-51f78a84.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 0px;}}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e8cad69e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8cad69e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e8cad69e{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8cad69e{width: 100%;}.wp-block-uagb-container.uagb-block-e8cad69e{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-e8cad69e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-e8cad69e{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0921a5e7 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0921a5e7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0921a5e7{box-shadow: 0px 0px   #00000070 ;padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 20px;column-gap: 20px;max-width: 100% !important;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-0921a5e7{width: 100%;}.wp-block-uagb-container.uagb-block-0921a5e7{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;max-width:  !important;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-0921a5e7{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-0921a5e7{padding-top: 10px;padding-bottom: 10px;padding-left: 10px;padding-right: 10px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;max-width: 100% !important;}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:14:{i:0;s:14:\"core\/paragraph\";i:1;s:12:\"core\/heading\";i:2;s:15:\"core\/categories\";i:3;s:17:\"core\/latest-posts\";i:4;s:14:\"core\/tag-cloud\";i:5;s:11:\"core\/search\";i:6;s:9:\"core\/list\";i:7;s:14:\"core\/list-item\";i:8;s:14:\"uagb\/icon-list\";i:9;s:20:\"uagb\/icon-list-child\";i:10;s:10:\"core\/group\";i:11;s:14:\"uagb\/container\";i:12;s:10:\"core\/image\";i:13;s:17:\"uagb\/loop-builder\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1778702897\";s:6:\"gfonts\";a:1:{s:7:\"Default\";a:2:{s:10:\"fontfamily\";s:7:\"Default\";s:12:\"fontvariants\";a:0:{}}}s:10:\"gfonts_url\";s:77:\"https:\/\/fonts.googleapis.com\/css?family=Default&subset=latin&display=fallback\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Johannes Ahrends","author_link":"https:\/\/carajandb.com\/en\/author\/9aa6cdb2095bd409\/"},"uagb_comment_info":0,"uagb_excerpt":"April 15th was patch day again. New security patches, patch sets, release update and whatever they are named became available. On the same day Oracle announced that for 12.2.0.1 a &#8220;Limited Error Correction Support&#8221; will be offered. Limited Error Correction Support According to Oracle the reason for this support extension is to give customers more&hellip;","_links":{"self":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/posts\/7677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/comments?post=7677"}],"version-history":[{"count":7,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/posts\/7677\/revisions"}],"predecessor-version":[{"id":7697,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/posts\/7677\/revisions\/7697"}],"wp:attachment":[{"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/media?parent=7677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/categories?post=7677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carajandb.com\/en\/wp-json\/wp\/v2\/tags?post=7677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}